{"id":86354,"date":"2026-09-01T07:51:37","date_gmt":"2026-09-01T06:51:37","guid":{"rendered":"https:\/\/herzogtum-direkt.de\/?p=86354"},"modified":"2026-09-01T08:46:25","modified_gmt":"2026-09-01T07:46:25","slug":"astronomiekurs-an-der-vhs-berkenthin-startet","status":"publish","type":"post","link":"https:\/\/herzogtum-direkt.de\/index.php\/2026\/09\/01\/astronomiekurs-an-der-vhs-berkenthin-startet\/","title":{"rendered":"Astronomiekurs an der VHS Berkenthin startet"},"content":{"rendered":"<p><strong>Berkenthin (fs).<\/strong> Am Mittwoch, den 9. September 2026 um 19.30 Uhr beginnt in der VHS Berkenthin wieder ein neuer 10-teiliger Astronomie-Kurs.\u00a0Eingeladen sind alle, die einen Einblick in die Astronomie gewinnen m\u00f6chten. Vorkenntnisse sind nicht erforderlich.<\/p>\n<p>Zum Kursumfang geh\u00f6rt die Orientierung am Sternenhimmel nach markanten Sternbildern und Sternen und die Bedienung von astronomischen Teleskopen und anderen optischen Hilfsmitteln.<\/p>\n<p>Auch zu interessanten kosmologischen Fragen wird Bezug genommen &#8211; zum Beispiel:<\/p>\n<p>\u00a0 &#8211; woher kommen die Atome, aus denen wir bestehen?<br \/>\n\u00a0 &#8211; Ist unsere Zivilisation einzigartig im Universum?<br \/>\n\u00a0 &#8211; wie gro\u00df ist das Universum?<\/p>\n<p>Bei klarem Wetter begibt sich der Astrokurs nach drau\u00dfen zum astronomischen Beobachtungsplatz bei Sierksrade, um gemeinsam einen Blick in den Sternenhimmel zu werfen &#8211; bei hei\u00dfem Tee und Keksen. Termine immer Mittwochs, vom 9. September bis 25. November, 19.30 Uhr bis 21 Uhr, Stecknitz-Schule Berkenthin, Berliner Str. 20 in Berkenthin.\u00a0Weitere Infos unter:\u00a0<a class=\"moz-txt-link-abbreviated\" href=\"http:\/\/www.vhs-berkenthin.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.vhs-berkenthin.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berkenthin (fs). Am Mittwoch, den 9. September 2026 um 19.30 Uhr beginnt in der VHS Berkenthin wieder ein neuer 10-teiliger Astronomie-Kurs.\u00a0Eingeladen sind alle, die einen Einblick in die Astronomie gewinnen m\u00f6chten. Vorkenntnisse sind nicht erforderlich. Zum Kursumfang geh\u00f6rt die Orientierung am Sternenhimmel nach markanten Sternbildern und Sternen und die Bedienung von astronomischen Teleskopen und anderen [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":86355,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","share_position":"top","share_float_style":"share-monocrhome","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"1","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"jnews_post_split":{"post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[65,63,1237],"tags":[1267,1266],"class_list":["post-86354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amt-berkenthin","category-herzogtum-lauenburg","category-umweltnatur","tag-astronomie","tag-vhs-berkenthin"],"_links":{"self":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/86354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/comments?post=86354"}],"version-history":[{"count":1,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/86354\/revisions"}],"predecessor-version":[{"id":86356,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/86354\/revisions\/86356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media\/86355"}],"wp:attachment":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media?parent=86354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/categories?post=86354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/tags?post=86354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}