{"id":80112,"date":"2026-02-04T10:19:29","date_gmt":"2026-02-04T09:19:29","guid":{"rendered":"https:\/\/herzogtum-direkt.de\/?p=80112"},"modified":"2026-02-04T10:20:33","modified_gmt":"2026-02-04T09:20:33","slug":"freisprechung-im-metallhandwerk-fuenf-neue-fachkraefte-starten-ins-berufsleben","status":"publish","type":"post","link":"https:\/\/herzogtum-direkt.de\/index.php\/2026\/02\/04\/freisprechung-im-metallhandwerk-fuenf-neue-fachkraefte-starten-ins-berufsleben\/","title":{"rendered":"Freisprechung im Metallhandwerk: F\u00fcnf neue Fachkr\u00e4fte starten ins Berufsleben"},"content":{"rendered":"\n<p><strong>M\u00f6lln (pm).<\/strong> In feierlichem Rahmen fand im Quellenhof in M\u00f6lln am Freitag, 30. Januar 2026 die Freisprechung der Metallbauer-Innung statt. Thorsten Przybyl, Obermeister der Innung des Metallhandwerks, sprach f\u00fcnf junge Metallbauer offiziell von den Pflichten ihres Ausbildungsvertrages frei und w\u00fcrdigte damit den erfolgreichen Abschluss ihrer Ausbildung.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1000\" height=\"609\" src=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/06\/Arbeitsmarkt-Handwerk-Fachkraefte-Pixabay.jpg\" alt=\"\" class=\"wp-image-51446\" srcset=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/06\/Arbeitsmarkt-Handwerk-Fachkraefte-Pixabay.jpg 1000w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/06\/Arbeitsmarkt-Handwerk-Fachkraefte-Pixabay-300x183.jpg 300w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/06\/Arbeitsmarkt-Handwerk-Fachkraefte-Pixabay-768x468.jpg 768w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/06\/Arbeitsmarkt-Handwerk-Fachkraefte-Pixabay-750x457.jpg 750w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">Foto: https:\/\/pixabay.com\/users\/alexas_fotos-686414\/?utm_source=link-attribution&#038;utm_medium=referral&#038;utm_campaign=image&#038;utm_content=3094035, hfr<\/figcaption><\/figure>\n\n\n\n<p>Vor Mitgliedern des Pr\u00fcfungsausschusses, dem Klassenlehrer, Eltern sowie Ausbildern erhielten die frischgebackenen Gesellen ihre Pr\u00fcfungszeugnisse. In seiner Ansprache betonte Obermeister Przybyl die Bedeutung des Handwerks f\u00fcr Wirtschaft und Gesellschaft und hob das Engagement sowie die fachlichen Leistungen der Absolventen hervor. Mit der Freisprechung beginne f\u00fcr die jungen Fachkr\u00e4fte ein neuer beruflicher Lebensabschnitt, verbunden mit Verantwortung, aber auch zahlreichen Chancen.<\/p>\n\n\n\n<p>Den Gl\u00fcckw\u00fcnschen schlossen sich die Mitglieder des Pr\u00fcfungsausschusses sowie der Klassenlehrer an. Sie w\u00fcrdigten besonders die Ausdauer und den Einsatz, den die Auszubildenden w\u00e4hrend ihrer Lehrzeit gezeigt haben.<\/p>\n\n\n\n<p>Als Innungsbester wurde Louis Vokuhl ausgezeichnet. Er absolvierte seine Ausbildung bei der Schlosserei und Metallbau Zwiebelmann in Reinfeld und \u00fcberzeugte mit besonders herausragenden Pr\u00fcfungsleistungen.<\/p>\n\n\n\n<p>Freigesprochen wurden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Fabian Breuhahn<\/strong>, ausgebildet bei Matthias Schernikau, M\u00f6hnsen<\/li>\n\n\n\n<li><strong>Andrii Harnik<\/strong>, ausgebildet bei Schlosserei Dreves, Inhaber C. Bethke e. K., Schwarzenbek<\/li>\n\n\n\n<li><strong>Thomas Andr\u00e9 Kie\u00dfig<\/strong>, ausgebildet bei Przybyl MeisterMetall GmbH &amp; Co. KG, Breitenfelde<\/li>\n\n\n\n<li><strong>Vincent Meyer<\/strong>, ausgebildet bei Matthias Schernikau, M\u00f6hnsen<\/li>\n\n\n\n<li><strong>Louis Vokuhl<\/strong>, ausgebildet bei Schlosserei und Metallbau Zwiebelmann GmbH, Reinfeld<\/li>\n<\/ul>\n\n\n\n<p>Die Innung des Metallhandwerks gratuliert allen Junggesellen herzlich zur bestandenen Pr\u00fcfung und w\u00fcnscht ihnen f\u00fcr ihren weiteren Berufsweg viel Erfolg, Freude am Handwerk und stets eine sichere Hand.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00f6lln (pm). In feierlichem Rahmen fand im Quellenhof in M\u00f6lln am Freitag, 30. Januar 2026 die Freisprechung der Metallbauer-Innung statt. Thorsten Przybyl, Obermeister der Innung des Metallhandwerks, sprach f\u00fcnf junge Metallbauer offiziell von den Pflichten ihres Ausbildungsvertrages frei und w\u00fcrdigte damit den erfolgreichen Abschluss ihrer Ausbildung. Vor Mitgliedern des Pr\u00fcfungsausschusses, dem Klassenlehrer, Eltern sowie Ausbildern [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":80116,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[63,74,66],"tags":[3399,1983],"class_list":["post-80112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-herzogtum-lauenburg","category-jugend-direkt","category-moelln","tag-freisprechnung","tag-metall-handwerk"],"_links":{"self":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/80112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/comments?post=80112"}],"version-history":[{"count":2,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/80112\/revisions"}],"predecessor-version":[{"id":80119,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/80112\/revisions\/80119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media\/80116"}],"wp:attachment":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media?parent=80112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/categories?post=80112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/tags?post=80112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}