{"id":77438,"date":"2025-11-03T09:28:00","date_gmt":"2025-11-03T08:28:00","guid":{"rendered":"https:\/\/herzogtum-direkt.de\/?p=77438"},"modified":"2025-11-03T09:28:00","modified_gmt":"2025-11-03T08:28:00","slug":"neuer-stadtjugendpfleger-in-geesthacht","status":"publish","type":"post","link":"https:\/\/herzogtum-direkt.de\/index.php\/2025\/11\/03\/neuer-stadtjugendpfleger-in-geesthacht\/","title":{"rendered":"Neuer Stadtjugendpfleger in Geesthacht"},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong>Geesthacht (pm).<\/strong> \u201eJugendliche brauchen nicht viel: Manchmal brauchen Sie nur ein Dach&#8230;\u201c, davon ist Sebastian Schr\u00f6der \u00fcberzeugt. Er ist Geesthachts neuer Stadtjugendpfleger und damit ein Bindeglied zwischen der Stadtverwaltung und den jungen Leuten Geesthachts sowie deren Familien. \u201eIch rede viel mit Kindern und Jugendlichen, mache mir ein Bild von ihren W\u00fcnschen und Bed\u00fcrfnissen. Aber auch Elternteilen steht meine T\u00fcr offen. Ich spreche mit ihnen zum Beispiel \u00fcber die Freizeitangebote f\u00fcr Jugendliche und ihre Familien in unserer Stadt, \u00fcber die Spielpl\u00e4tze und die Aktivit\u00e4ten von Geesthachter Vereinen. Bei Problemlagen kann ich auch gerne Kontakte zu anderen Stellen vermitteln, die im Einzelfall dann vielleicht noch konkreter weiterhelfen k\u00f6nnen. Auch die regelm\u00e4\u00dfige \u00dcberplanung der Spielpl\u00e4tze sowie andere Kinder- und Jugendbeteiligungen geh\u00f6ren in meinen Verantwortungsbereich. Au\u00dferdem halte ich den Kontakt zum Kreis Herzogtum Lauenburg, der ebenfalls Aufgaben im Bereich Jugendpflege \u00fcbernimmt\u201c, beschreibt er eine von zwei Haupts\u00e4ulen seiner Arbeit.<\/p>\n<figure id=\"attachment_77439\" aria-describedby=\"caption-attachment-77439\" style=\"width: 600px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-medium wp-image-77439\" src=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2025\/11\/Josefine-Dettmer-und-Sebastian-Schroeder-Geesthacht-Stadtjugendpflege-2025-600x383.jpg\" alt=\"\" width=\"600\" height=\"383\" srcset=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2025\/11\/Josefine-Dettmer-und-Sebastian-Schroeder-Geesthacht-Stadtjugendpflege-2025-600x383.jpg 600w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2025\/11\/Josefine-Dettmer-und-Sebastian-Schroeder-Geesthacht-Stadtjugendpflege-2025-768x490.jpg 768w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2025\/11\/Josefine-Dettmer-und-Sebastian-Schroeder-Geesthacht-Stadtjugendpflege-2025.jpg 1000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-77439\" class=\"wp-caption-text\">Arbeiten im Team: Geesthachts neuer Stadtjugendpfleger Sebastian Schr\u00f6der und Josefine Dettmer von der Kommunalen Fachstelle f\u00fcr Jugendbeteiligung, die aktuell die Wahl des Geesthachter Kinder- und Jugendbeirats (17. \u2013 23. November 2025) organisiert, sind beide in den R\u00e4umen an der Schillerstra\u00dfe 7 anzutreffen. Foto: Stadt Geesthacht, hfr<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\">Der zweite gro\u00dfe Schwerpunkt seines Alltags: Die organisatorische Aufstellung der Stadtjugendpflege: \u201eWir m\u00f6chten neues Personal gewinnen, damit wir in Zukunft f\u00fcr die Herausforderungen gut aufgestellt sind\u201c, sagt Sebastian Schr\u00f6der, der als Leiter der Stadtjugendpflege f\u00fcr die Teams des Jugendzentrums Alter Bahnhof, des Jugendhauses D\u00fcne, des Spielmobils und der aufsuchenden Jugendpflege den Hut aufhat. Wer \u00fcbernimmt k\u00fcnftig welche Aufgaben? An welchen Stellen k\u00f6nnen Profile gesch\u00e4rft oder Angebote ausgebaut werden? Und wie kann es zwischen den verschiedenen Stellen, die im Bereich Jugendpflege aktiv sind, noch mehr Hand in Hand gehen? Das alles sind Fragen, mit denen sich Sebastian Schr\u00f6der besch\u00e4ftigt. \u201eKlar muss aber auch sein: Um qualitativ hochwertige Arbeit leisten zu k\u00f6nnen, ben\u00f6tigen wir Fachkr\u00e4fte.\u201c Darum ist die Gewinnung von Fachleuten ebenfalls ganz oben auf Sebastian Schr\u00f6ders Agenda. \u201eMehrere Stellen seien aktuell im Bereich Jugendpflege unbesetzt\u201c, merkt Geesthachts neuer Stadtjugendpfleger an, der selber ausgebildeter Gas- und Wasserinstallateur ist und nach mehreren Jahren Berufspraxis auf dem zweiten Bildungsweg das Abitur nachholte und dann Soziale Arbeit an der Fachhochschule Kiel studierte. \u201eIch habe dann einen Weg eingeschlagen, der zu der \u201asozialen Ader\u2018 passt, die mir meine Freunde schon immer nachgesagt haben\u201c, sagt der 43-J\u00e4hrige, der seit zehn Jahren in Boizenburg lebt und in Geesthacht schon seit Jahren gerne seine Freizeit verbringt. Bevor er das B\u00fcro der Stadtjugendpflege an der Schillerstra\u00dfe 7 bezogen hat, war er unter anderem in Kiel in der Migrationsberatung sowie in der offenen Jugendarbeit t\u00e4tig, leitete Wohngruppen (station\u00e4re und mobile Kinder- und Jugendhilfe) und unterst\u00fctzte langzeiterkrankte sowie behinderte Jugendliche in ihrer beruflichen Rehabilitation.<\/p>\n<p style=\"font-weight: 400;\">Die ersten Wochen seiner T\u00e4tigkeit in Geesthacht hat er vor allem f\u00fcr zwei Dinge genutzt: Eine Bestandsaufnahme \u2013 und Gespr\u00e4che, Gespr\u00e4che, Gespr\u00e4che. \u201eIch habe schon viele Stationen in der Kinder- und Jugendarbeit hinter mir und kann voller \u00dcberzeugung sagen: \u201eToll ist, dass Geesthacht sehr viel f\u00fcr Kinder und Jugendliche zu bieten hat, obwohl es hier keinen Stadtjugendring oder \u00e4hnliche Strukturen gibt, wie es in anderen mittelgro\u00dfen St\u00e4dten vorhanden ist. Das ist toll! Aber klar ist auch: Geesthacht muss mehr R\u00e4ume f\u00fcr Jugendliche schaffen\u201c, findet Sebastian Schr\u00f6der klare Worte. Ein Raum, an dem sich das Geschehen konzentriere, reiche nicht. \u201eIch kenne das auch aus anderen St\u00e4dten: Kinder sind immer \u00fcberall gerne gesehen, bei Jugendlichen ist das leider nicht so. Wenn sie sich an einem \u00f6ffentlichen Ort in einer gr\u00f6\u00dferen Gruppe treffen, wird das h\u00e4ufiger als st\u00f6rend empfunden, was sehr schade ist. Jedes Alter hat doch eine gute Seite\u201c, betont Sebastian Schr\u00f6der. Wer zu ihm Kontakt aufnehmen m\u00f6chte, ist in den R\u00e4umen an der Schillerstra\u00dfe 7 willkommen. Zudem ist er telefonisch unter 04152 131451 sowie per E-Mail unter\u00a0<a href=\"mailto:sebastian.schroeder@geesthacht.de\" target=\"_blank\" rel=\"noopener\">sebastian.schroeder@geesthacht.de<\/a>\u00a0erreichbar.<\/p>\n<p style=\"font-weight: 400;\">Am Dienstag, 4. November 2025, stellt Sebastian Schr\u00f6der sich und seine Arbeit im Sozialausschuss vor. Die Sitzung beginnt um 18 Uhr im Rathaus (Markt 15) und ist \u00f6ffentlich. Wer sich aus erster Hand \u00fcber die Stadtjugendpflege informieren m\u00f6chte, ist dort willkommen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Geesthacht (pm). \u201eJugendliche brauchen nicht viel: Manchmal brauchen Sie nur ein Dach&#8230;\u201c, davon ist Sebastian Schr\u00f6der \u00fcberzeugt. Er ist Geesthachts neuer Stadtjugendpfleger und damit ein Bindeglied zwischen der Stadtverwaltung und den jungen Leuten Geesthachts sowie deren Familien. \u201eIch rede viel mit Kindern und Jugendlichen, mache mir ein Bild von ihren W\u00fcnschen und Bed\u00fcrfnissen. Aber auch [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":77440,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":""},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"jnews_post_split":{"post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[2625,63,74],"tags":[249,3314],"class_list":["post-77438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geesthacht","category-herzogtum-lauenburg","category-jugend-direkt","tag-geesthacht","tag-stadtjugendpflege"],"_links":{"self":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/77438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/comments?post=77438"}],"version-history":[{"count":1,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/77438\/revisions"}],"predecessor-version":[{"id":77441,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/77438\/revisions\/77441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media\/77440"}],"wp:attachment":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media?parent=77438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/categories?post=77438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/tags?post=77438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}