{"id":77285,"date":"2025-10-28T09:30:09","date_gmt":"2025-10-28T08:30:09","guid":{"rendered":"https:\/\/herzogtum-direkt.de\/?p=77285"},"modified":"2025-10-28T09:30:09","modified_gmt":"2025-10-28T08:30:09","slug":"infos-zum-internationalen-maennergesundheitstag","status":"publish","type":"post","link":"https:\/\/herzogtum-direkt.de\/index.php\/2025\/10\/28\/infos-zum-internationalen-maennergesundheitstag\/","title":{"rendered":"Infos zum Internationalen M\u00e4nnergesundheitstag"},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong>Dassendorf (pm).<\/strong>\u00a0Prostatakrebs geht jeden etwas an, k\u00f6nnte er doch im Umfeld jederzeit auftreten. Deshalb steht am kommenden Montag, 3. November 2025 die Gleichstellungsbeauftragte des Amtes Hohe Elbgeest, Nina Stiewink, im B\u00fcrgerzentrum Dassendorf am Falkenring 1 und verteilt Informationsbrosch\u00fcren zum Thema \u201eVorsorge bei Prostatakrebs\u201c. Zudem hat sie kostenlose \u00dcbersichtskalender f\u00fcr 2026 in Postkartengr\u00f6\u00dfe dabei.<\/p>\n<figure id=\"attachment_77286\" aria-describedby=\"caption-attachment-77286\" style=\"width: 450px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-medium wp-image-77286\" src=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2025\/10\/Tag-der-Maennergesundheit-2025-in-Dassendorf-Foto-Vanessa-Riggert-hfr-450x600.jpg\" alt=\"\" width=\"450\" height=\"600\" srcset=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2025\/10\/Tag-der-Maennergesundheit-2025-in-Dassendorf-Foto-Vanessa-Riggert-hfr-450x600.jpg 450w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2025\/10\/Tag-der-Maennergesundheit-2025-in-Dassendorf-Foto-Vanessa-Riggert-hfr-rotated.jpg 500w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><figcaption id=\"caption-attachment-77286\" class=\"wp-caption-text\">Tag der M\u00e4nnergesundheit 2025 in Dassendorf Foto: Vanessa Riggert, hfr<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\">Amtsdirektor Torge Sommerkorn unterst\u00fctzt die Aktion mit seinem Foto und dem Zitat: \u201cGesundheit ist Zukunft: Krebsvorsorge macht den Unterschied.\u201c Frau Stiewink ist das Thema im vergangenen Jahr wichtig geworden: \u201eDa habe ich Brosch\u00fcren und Kalender unter den Kolleginnen und Kollegen verteilt. Dabei wurde in vielen Gespr\u00e4chen deutlich, wie hoch die Betroffenheit ist \u2013 und manchmal auch die Verzweiflung dar\u00fcber, dass die Vorsorge vernachl\u00e4ssigt wurde.\u201c In den Gespr\u00e4chen spiegelte sich die Erfahrung, dass M\u00e4nner sich weniger um ihre Gesundheit k\u00fcmmern, dies manchmal als Schw\u00e4che ansehen.<\/p>\n<p style=\"font-weight: 400;\">Aus diesem Grund heraus wurde im Jahr 2000 der \u201eWeltm\u00e4nnertag\u201c gegr\u00fcndet. Es ist ein Aktionstag zur M\u00e4nnergesundheit, der j\u00e4hrlich am 3. November stattfindet. Dieser sollte, laut Aussage von Michail Gorbatschow als Schirmherr, das Bewusstsein der M\u00e4nner im gesundheitlichen Bereich erweitern. Heute stehen vor allem rechtzeitige Gesundheitsvorsorge und die realistische Einsch\u00e4tzung der eigenen gesundheitlichen Verfassung und Risiken im Vordergrund. Er ist nicht zu verwechseln mit dem Internationalen M\u00e4nnertag, welcher am 19. November eines jeden Jahres stattfindet.<\/p>\n<p style=\"font-weight: 400;\">Ins Leben gerufen wurde der erste Weltm\u00e4nnertag im Jahr 2000 von Andrologen der Universit\u00e4t Wien. Gemeinsam mit der Stadt Wien, der Gorbatschow-Stiftung, Medical Connection und United Nations Office at Vienna (UNOV) wurde er das erste Mal offiziell 2000 in Wien veranstaltet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dassendorf (pm).\u00a0Prostatakrebs geht jeden etwas an, k\u00f6nnte er doch im Umfeld jederzeit auftreten. Deshalb steht am kommenden Montag, 3. November 2025 die Gleichstellungsbeauftragte des Amtes Hohe Elbgeest, Nina Stiewink, im B\u00fcrgerzentrum Dassendorf am Falkenring 1 und verteilt Informationsbrosch\u00fcren zum Thema \u201eVorsorge bei Prostatakrebs\u201c. Zudem hat sie kostenlose \u00dcbersichtskalender f\u00fcr 2026 in Postkartengr\u00f6\u00dfe dabei. Amtsdirektor Torge [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":55401,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":""},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"jnews_post_split":{"post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[2652,75,63],"tags":[513,1183,3709],"class_list":["post-77285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amt-hohe-elbgeest","category-gesundheit","category-herzogtum-lauenburg","tag-dassendorf","tag-gesundheitstipps","tag-gleichstellungsbeauftragte"],"_links":{"self":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/77285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/comments?post=77285"}],"version-history":[{"count":2,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/77285\/revisions"}],"predecessor-version":[{"id":77291,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/77285\/revisions\/77291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media\/55401"}],"wp:attachment":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media?parent=77285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/categories?post=77285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/tags?post=77285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}