{"id":71320,"date":"2025-04-03T04:47:05","date_gmt":"2025-04-03T03:47:05","guid":{"rendered":"https:\/\/herzogtum-direkt.de\/?p=71320"},"modified":"2025-04-04T10:09:00","modified_gmt":"2025-04-04T09:09:00","slug":"baustart-am-stadtseeanleger-neue-steganlage-entsteht","status":"publish","type":"post","link":"https:\/\/herzogtum-direkt.de\/index.php\/2025\/04\/03\/baustart-am-stadtseeanleger-neue-steganlage-entsteht\/","title":{"rendered":"Baustart am Stadtseeanleger: Neue Steganlage entsteht"},"content":{"rendered":"<p><strong>M\u00f6lln (pm).<\/strong>\u00a0Die Bauarbeiten am neuen Stadtseeanleger in M\u00f6lln machen Fortschritte: Die Einrichtung der Baustellenfl\u00e4chen an der Wassertorbr\u00fccke f\u00fcr den Neubau der Steganlage am Stadtseeanleger ist inzwischen abgeschlossen.<\/p>\n<p>Auf der Gr\u00fcnfl\u00e4che am Stadtsee wurde eine provisorische Stra\u00dfe gebaut, die von der Ratzeburger Stra\u00dfe bis zum Ufer f\u00fchrt. \u00dcber diese Stra\u00dfe wurde ein gro\u00dfer Arbeitsponton, bestehend aus f\u00fcnf einzelnen Pontons, mit einem Kran in den Stadtsee gebracht. Dieser Ponton dient als schwimmende Arbeitsplattform f\u00fcr die Bauarbeiten. Anschlie\u00dfend wurde ein Bagger auf den Ponton gesetzt, der f\u00fcr die weiteren Arbeiten vor Ort ben\u00f6tigt wird.\u00a0Der Ponton kann nun mit einem Schubboot zum Stadtseeanleger und zur\u00fcck transportiert werden.<\/p>\n<p>Am 11. M\u00e4rz 2025 wurden Taucher eingesetzt, um den Bereich des Stadtseeanlegers zu untersuchen. Dabei ging es vor allem um die alten Holzpf\u00e4hle, die teilweise unter Wasser liegen, und die Stellen, an denen die neuen Pf\u00e4hle (Dalben) gesetzt werden sollen.<\/p>\n<figure id=\"attachment_71321\" aria-describedby=\"caption-attachment-71321\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-full wp-image-71321\" src=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2025\/04\/Blick-vom-Stadtseeanleger-Foto-Katrin-Jester-Stadt-Moelln.jpg\" alt=\"\" width=\"1000\" height=\"579\" srcset=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2025\/04\/Blick-vom-Stadtseeanleger-Foto-Katrin-Jester-Stadt-Moelln.jpg 1000w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2025\/04\/Blick-vom-Stadtseeanleger-Foto-Katrin-Jester-Stadt-Moelln-600x347.jpg 600w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2025\/04\/Blick-vom-Stadtseeanleger-Foto-Katrin-Jester-Stadt-Moelln-768x445.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-71321\" class=\"wp-caption-text\">Blick vom Stadtseeanleger. Foto: Katrin Jester (Stadt M\u00f6lln)<\/figcaption><\/figure>\n<p>Die Taucher suchten nach gesch\u00fctzten Muschelarten, die m\u00f6glicherweise umgesiedelt werden m\u00fcssen. Die Untersuchung ergab, dass keine gesch\u00fctzten Gro\u00dfmuscheln in dem Bereich leben, sodass die gezogenen Pf\u00e4hle nicht wie zun\u00e4chst geplant mit den gesch\u00fctzten Muscheln im See an anderer Stelle versenkt werden m\u00fcssen.<\/p>\n<p>In den kommenden Tagen werden die alten Holzpf\u00e4hle entfernt und die neuen, 27 Meter langen Pf\u00e4hle (Dalben) in den Untergrund des Stadtsees gerammt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00f6lln (pm).\u00a0Die Bauarbeiten am neuen Stadtseeanleger in M\u00f6lln machen Fortschritte: Die Einrichtung der Baustellenfl\u00e4chen an der Wassertorbr\u00fccke f\u00fcr den Neubau der Steganlage am Stadtseeanleger ist inzwischen abgeschlossen. Auf der Gr\u00fcnfl\u00e4che am Stadtsee wurde eine provisorische Stra\u00dfe gebaut, die von der Ratzeburger Stra\u00dfe bis zum Ufer f\u00fchrt. \u00dcber diese Stra\u00dfe wurde ein gro\u00dfer Arbeitsponton, bestehend aus [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":71323,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"1","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"jnews_post_split":{"post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[63,66,2],"tags":[133],"class_list":["post-71320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-herzogtum-lauenburg","category-moelln","category-startseite","tag-moelln"],"_links":{"self":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/71320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/comments?post=71320"}],"version-history":[{"count":1,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/71320\/revisions"}],"predecessor-version":[{"id":71324,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/71320\/revisions\/71324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media\/71323"}],"wp:attachment":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media?parent=71320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/categories?post=71320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/tags?post=71320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}