{"id":64597,"date":"2024-09-11T06:42:00","date_gmt":"2024-09-11T04:42:00","guid":{"rendered":"https:\/\/herzogtum-direkt.de\/?p=64597"},"modified":"2024-09-10T11:48:52","modified_gmt":"2024-09-10T09:48:52","slug":"freiflaechen-photovoltaik-herausforderungen-und-chancen","status":"publish","type":"post","link":"https:\/\/herzogtum-direkt.de\/index.php\/2024\/09\/11\/freiflaechen-photovoltaik-herausforderungen-und-chancen\/","title":{"rendered":"\u201aFreifl\u00e4chen-Photovoltaik \u2013 Herausforderungen und Chancen\u2018"},"content":{"rendered":"\n<p><strong>M\u00f6lln (pm). <\/strong>Der Landtagsabgeordnete Oliver Brandt von B\u00fcndnis 90\/Die Gr\u00fcnen l\u00e4dt am Donnerstag, 19. September zu einer Informationsveranstaltung im Quellenhof in M\u00f6lln zum Thema Freifl\u00e4chen-Photovoltaik ein. Der Beginn der Veranstaltung ist um 19 Uhr.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1000\" height=\"715\" src=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2024\/09\/Oliver-Brandt-MdL-Foto-Dirk-Eisermann-hfr.png\" alt=\"\" class=\"wp-image-64598\" srcset=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2024\/09\/Oliver-Brandt-MdL-Foto-Dirk-Eisermann-hfr.png 1000w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2024\/09\/Oliver-Brandt-MdL-Foto-Dirk-Eisermann-hfr-300x215.png 300w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2024\/09\/Oliver-Brandt-MdL-Foto-Dirk-Eisermann-hfr-768x549.png 768w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2024\/09\/Oliver-Brandt-MdL-Foto-Dirk-Eisermann-hfr-120x86.png 120w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2024\/09\/Oliver-Brandt-MdL-Foto-Dirk-Eisermann-hfr-350x250.png 350w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2024\/09\/Oliver-Brandt-MdL-Foto-Dirk-Eisermann-hfr-750x536.png 750w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">Oliver Brandt, MdL Foto Dirk Eisermann, hfr<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Deutschland hat die gesetzliche Vorgabe, bis 2045 klimaneutral zu werden, Schleswig-Holstein plant dieses Ziel bereits 2040 zu erreichen. Dazu geh\u00f6ren eine CO2-freie Stromproduktion und der weitere Ausbau der Erneuerbaren Energien wie der Solarenergie. Mit der Landtagsabgeordneten Ulrike T\u00e4ck (B 90\/Die Gr\u00fcnen) sowie VertreterInnen von SH Netz, dem Landesverband Erneuerbare Energien und der Kreisverwaltung diskutiert Oliver Brandt \u00fcber die Chancen und H\u00fcrden beim Ausbau von Photovoltaik auf Freifl\u00e4chen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00f6lln (pm). Der Landtagsabgeordnete Oliver Brandt von B\u00fcndnis 90\/Die Gr\u00fcnen l\u00e4dt am Donnerstag, 19. September zu einer Informationsveranstaltung im Quellenhof in M\u00f6lln zum Thema Freifl\u00e4chen-Photovoltaik ein. Der Beginn der Veranstaltung ist um 19 Uhr. Deutschland hat die gesetzliche Vorgabe, bis 2045 klimaneutral zu werden, Schleswig-Holstein plant dieses Ziel bereits 2040 zu erreichen. Dazu geh\u00f6ren eine [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[63,66,1237],"tags":[144,133,2628,3329],"class_list":["post-64597","post","type-post","status-publish","format-standard","hentry","category-herzogtum-lauenburg","category-moelln","category-umweltnatur","tag-buendnis-90-die-gruene","tag-moelln","tag-photovoltaik","tag-veranstaltung"],"_links":{"self":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/64597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/comments?post=64597"}],"version-history":[{"count":1,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/64597\/revisions"}],"predecessor-version":[{"id":64599,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/64597\/revisions\/64599"}],"wp:attachment":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media?parent=64597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/categories?post=64597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/tags?post=64597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}