{"id":56747,"date":"2023-12-25T06:59:00","date_gmt":"2023-12-25T04:59:00","guid":{"rendered":"https:\/\/herzogtum-direkt.de\/?p=56747"},"modified":"2023-12-23T19:10:43","modified_gmt":"2023-12-23T17:10:43","slug":"ausgezeichnet-verein-ratzeburg-hilft","status":"publish","type":"post","link":"https:\/\/herzogtum-direkt.de\/index.php\/2023\/12\/25\/ausgezeichnet-verein-ratzeburg-hilft\/","title":{"rendered":"Ausgezeichnet: Verein \u201eRatzeburg hilft&#8220;\u00a0"},"content":{"rendered":"\n<p><strong>Ratzeburg (tbi).<\/strong>&nbsp;Dass die Unterst\u00fctzung und die konkreten Ma\u00dfnahmen, die der Verein \u201eRatzeburg hilft&#8220; seit Beginn des \u00dcberfalles auf die Ukraine f\u00fcr die Menschen dort und f\u00fcr Gefl\u00fcchtete hier leistet, eine enorme Bedeutung hat, wird nicht nur bei uns gew\u00fcrdigt. Jetzt haben die Verantwortlichen des Vereins Orden, Medaillen und Urkunden aus der Ukraine erhalten. Es ist ein weiterer Beleg daf\u00fcr, dass die Unterst\u00fctzung von \u201eRatzeburg hilft&#8220; eins zu eins dort in der Ukraine ankommt, wo Hilfe unmittelbar gebraucht wird. Der Verein bittet aber auch weiterhin um Unterst\u00fctzung, vor allem f\u00fcr die medizinische Versorgung in den vom Krieg gezeichneten Regionen.&nbsp;<\/p>\n\n\n\n<p>Die symbolischen Danksagungen aus der Ukraine gelten allen, die sich durch Spenden, und durch Tatkraft f\u00fcr die Hilfsleistungen seit Gr\u00fcndung des Vereines engagiert haben. Aber nat\u00fcrlich darf das Team um die Vereinsvorsitzende Ekaterina Turowski auch etwas stolz darauf sein, was der Verein bislang schon bewegt hat. Gemeinsam mit Ehemann Martin Turowski und dem Ehepaar Ludmilla und Kai Feller warb Turowski im Burgtheater f\u00fcr weitere Unterst\u00fctzung des Vereins. Beide Frauen stammen aus der Ukraine, leben jetzt schon viele Jahre in Deutschland. Kennengelernt haben sie sich unmittelbar nach dem 24. Februar 2022, dem Beginn der Angriffe, als es in Ratzeburg darum ging, schnell Hilfe zu leisten.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a97dafbbe26b&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a97dafbbe26b\" class=\"wp-block-image size-medium is-style-default wp-lightbox-container\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"56751\" src=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_03-Ukraine-Ratzeburg_hilft-Orden-ID3C2312-1000x667-1-300x200.jpg\" alt=\"\" class=\"wp-image-56751\" srcset=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_03-Ukraine-Ratzeburg_hilft-Orden-ID3C2312-1000x667-1-300x200.jpg 300w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_03-Ukraine-Ratzeburg_hilft-Orden-ID3C2312-1000x667-1-768x512.jpg 768w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_03-Ukraine-Ratzeburg_hilft-Orden-ID3C2312-1000x667-1-750x500.jpg 750w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_03-Ukraine-Ratzeburg_hilft-Orden-ID3C2312-1000x667-1.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Vergr\u00f6\u00dfern\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Medaille f\u00fcr \u201eRatzeburg hilft&#8220;. Foto: Thomas Biller <\/figcaption><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a97dafbbe5fa&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a97dafbbe5fa\" class=\"wp-block-image size-medium is-style-default wp-lightbox-container\"><img decoding=\"async\" width=\"300\" height=\"200\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"56750\" src=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_02-Auszeichnung-Ukraine-Verein_Ratzeburg_hilft-ID3C2309-1000x667-1-300x200.jpg\" alt=\"\" class=\"wp-image-56750\" srcset=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_02-Auszeichnung-Ukraine-Verein_Ratzeburg_hilft-ID3C2309-1000x667-1-300x200.jpg 300w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_02-Auszeichnung-Ukraine-Verein_Ratzeburg_hilft-ID3C2309-1000x667-1-768x512.jpg 768w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_02-Auszeichnung-Ukraine-Verein_Ratzeburg_hilft-ID3C2309-1000x667-1-750x500.jpg 750w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_02-Auszeichnung-Ukraine-Verein_Ratzeburg_hilft-ID3C2309-1000x667-1.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Vergr\u00f6\u00dfern\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Dankesplakette von einer Menschenrechtsorganisation aus der Ukraine. Foto: Thomas Biller <\/figcaption><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a97dafbbe8cf&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a97dafbbe8cf\" class=\"wp-block-image size-medium is-style-default wp-lightbox-container\"><img decoding=\"async\" width=\"300\" height=\"199\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"56749\" src=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_04-Urkunde-Ratzeburg-hilft-Auszeichnung-ID3C2314-1000x664-1-300x199.jpg\" alt=\"\" class=\"wp-image-56749\" srcset=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_04-Urkunde-Ratzeburg-hilft-Auszeichnung-ID3C2314-1000x664-1-300x199.jpg 300w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_04-Urkunde-Ratzeburg-hilft-Auszeichnung-ID3C2314-1000x664-1-768x510.jpg 768w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_04-Urkunde-Ratzeburg-hilft-Auszeichnung-ID3C2314-1000x664-1-750x498.jpg 750w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2023\/12\/Bild_04-Urkunde-Ratzeburg-hilft-Auszeichnung-ID3C2314-1000x664-1.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Vergr\u00f6\u00dfern\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Urkunde f\u00fcr \u201eRatzeburg hilft&#8220;. Foto: Thomas Biller <\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p>\u00dcber 50 Hilfstransporte hat \u201eRatzeburg hilft&#8220; seit bereits Anfang M\u00e4rz 2022 in die Ukraine organisiert. Waren und Hilfsg\u00fcter im Gesamtvolumenwert von eineinhalb Millionen Euro konnten den Menschen dort durch den Verein und die vielen Spenden zugutekommen. Heute gehe es vor allem darum, medizinischen Sachbedarf und medizinische Produkte liefern zu k\u00f6nnen. \u201eEs werden Laborger\u00e4te in den Kliniken gebraucht, aber auch Medikamente, die f\u00fcr uns hier selbstverst\u00e4ndlich sind, wie zum Beispiel Insulin&#8220;, berichtete Martin Turowski, der erst in diesem Fr\u00fchjahr einen Hilfstransport begleitet hat.&nbsp;<\/p>\n\n\n\n<p>\u00dcber pers\u00f6nliche Kontakte und verschiedene befreundete Vereine in der Ukraine wei\u00df \u201eRatzeburg hilft&#8220;, welche Dinge wo vor Ort dringend ben\u00f6tigt werden. \u201eDaher passen wir unsere Bitte um Spenden immer wieder an&#8220;, so Martin Turowski.&nbsp;<\/p>\n\n\n\n<p>Eine Plakette hat der Verein erhalten von der \u201eOrganisation zum Schutze der Menschenrechte in der Ukraine&#8220;. Es ist eine \u201eAuszeichnung f\u00fcr die humanit\u00e4re Unterst\u00fctzung der ukrainischen Bev\u00f6lkerung&#8220;. Medaillen kamen aus Ochtyrka, der Heimatstadt von Ekaterina Turowski, die, im Nordosten der Ukraine gelegen, von Russland stark attackiert wurde. Seit April 2022 ist die Region wieder befreit. \u201eJa, wir sind \u00fcber diese Auszeichnungen dankbar und stolz. Aber es ist eine R\u00fcckmeldung f\u00fcr alle Menschen hier in Ratzeburg und Umgebung, die uns unterst\u00fctzt haben und weiter unterst\u00fctzen. Ihre Hilfe kommt weiterhin zu 100 Prozent in der Ukraine an&#8220;, so Ekaterina Turowski.&nbsp;<\/p>\n\n\n\n<p>\u201eDie Dankbarkeit, dass sich fremde Menschen f\u00fcr sie engagieren, ist in der Ukraine riesengro\u00df&#8220;, wei\u00df Pastor Kai Feller, der ebenfalls Hilfstransporte begleitet hat. \u201eEs ist ein wichtiges Signal, dass die Menschen dort nicht vergessen sind&#8220;, so der engagierte Pastor. &nbsp;Hier vor Ort hat es \u201eRatzeburg hilft&#8220; vermocht, f\u00fcr vor dem Krieg aus der Ukraine Gefl\u00fcchtete 20 Wohnungen zu vermitteln. \u201eEinige davon hat der Verein selbst angemietet&#8220;, berichtete Martin Turowski.&nbsp;<\/p>\n\n\n\n<p>F\u00fcr Laborger\u00e4te und f\u00fcr Medikamente nimmt \u201eRatzeburg hilft&#8220; weiterhin gerne Geldspenden entgegen. Verein Ratzeburg hilft, IBAN DE79 2019 0109 0010 1995 30, Verwendungszweck: Ukraine. Als gemeinn\u00fctziger Verein stellt \u201eRatzeburg hilft&#8220; gerne Spendenbescheinigungen aus. Weitere Infos zum Verein finden sich <a href=\"http:\/\/www.ratzeburg-hilft.de\" data-type=\"link\" data-id=\"www.ratzeburg-hilft.de\">hier<\/a>.&nbsp;<\/p>\n\n\n\n<p>Aber auch Sachspenden sind willkommen, wenn in Arztpraxen oder anderen medizinischen Einrichtungen zum Beispiel Medikamente oder Hilfsmittel sich kurz vor oder nach Ablauf des Mindesthaltbarkeitsdatums befinden. \u201eWir senden alles, was helfen kann, in die Ukraine; dort entscheiden dann die \u00c4rzte vor Ort \u00fcber die Verwendung&#8220;, so Kai Feller.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ratzeburg (tbi).&nbsp;Dass die Unterst\u00fctzung und die konkreten Ma\u00dfnahmen, die der Verein \u201eRatzeburg hilft&#8220; seit Beginn des \u00dcberfalles auf die Ukraine f\u00fcr die Menschen dort und f\u00fcr Gefl\u00fcchtete hier leistet, eine enorme Bedeutung hat, wird nicht nur bei uns gew\u00fcrdigt. Jetzt haben die Verantwortlichen des Vereins Orden, Medaillen und Urkunden aus der Ukraine erhalten. Es ist [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":56748,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"Urkunden und Medaillen aus der Ukraine f\u00fcr das Engagement aus der Inselstadt ","format":"standard","video":"","gallery":"","source_name":"","source_url":"","via_name":"","via_url":"","jpwt_enable_post_donation":"0","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"0","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"0","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"0","show_popup_post":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"1","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"jnews_override_counter":{"override_view_counter":"0","view_counter_number":"0","override_share_counter":"0","share_counter_number":"0","override_like_counter":"0","like_counter_number":"0","override_dislike_counter":"0","dislike_counter_number":"0"},"jnews_post_split":{"enable_post_split":"0","post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[63,64,2],"tags":[114,3257,3263],"class_list":["post-56747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-herzogtum-lauenburg","category-ratzeburg","category-startseite","tag-ratzeburg","tag-ukraine","tag-vereinratzeburg-hilft"],"_links":{"self":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/56747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/comments?post=56747"}],"version-history":[{"count":3,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/56747\/revisions"}],"predecessor-version":[{"id":56754,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/56747\/revisions\/56754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media\/56748"}],"wp:attachment":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media?parent=56747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/categories?post=56747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/tags?post=56747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}