{"id":24407,"date":"2020-07-22T09:46:27","date_gmt":"2020-07-22T08:46:27","guid":{"rendered":"https:\/\/herzogtum-direkt.de\/?p=24407"},"modified":"2020-07-22T09:46:27","modified_gmt":"2020-07-22T08:46:27","slug":"sommer-sonne-juckreiz","status":"publish","type":"post","link":"https:\/\/herzogtum-direkt.de\/index.php\/2020\/07\/22\/sommer-sonne-juckreiz\/","title":{"rendered":"Sommer, Sonne, Juckreiz"},"content":{"rendered":"<figure id=\"attachment_24408\" aria-describedby=\"caption-attachment-24408\" style=\"width: 299px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2020\/07\/2020-ERGO-Ratgeber-Sonnenallergie-Digital.jpg\"><img decoding=\"async\" class=\" wp-image-24408\" src=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2020\/07\/2020-ERGO-Ratgeber-Sonnenallergie-Digital-200x300.jpg\" alt=\"\" width=\"299\" height=\"449\" srcset=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2020\/07\/2020-ERGO-Ratgeber-Sonnenallergie-Digital-200x300.jpg 200w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2020\/07\/2020-ERGO-Ratgeber-Sonnenallergie-Digital-280x420.jpg 280w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2020\/07\/2020-ERGO-Ratgeber-Sonnenallergie-Digital.jpg 426w\" sizes=\"(max-width: 299px) 100vw, 299px\" \/><\/a><figcaption id=\"caption-attachment-24408\" class=\"wp-caption-text\">Foto: ERGO Group<\/figcaption><\/figure>\n<p><strong>Herzogtum Lauenburg (pm).<\/strong> So sch\u00f6n es ist, in der Sonne zu liegen \u2013 manchmal endet ein ausgiebiges Sonnenbad mit R\u00f6tungen, juckenden Hautstellen oder Pusteln. Solche Symptome k\u00f6nnen auf eine Sonnenallergie hinweisen. Was das ist, wie Betroffene vorbeugen k\u00f6nnen und was der Unterschied ist zu einem Sonnenbrand, wei\u00df Dr. Wolfgang Reuter, Gesundheitsexperte der DKV.<\/p>\n<p>Was ist eine Sonnenallergie?<\/p>\n<p>Unter den umgangssprachlichen Begriff \u201eSonnenallergie\u201c fallen verschiedene Hautreaktionen, die zwar durch Sonnenlicht ausgel\u00f6st werden, aber oft nicht allergisch bedingt sind. Dabei ist in der Regel nicht ein \u201ezu viel\u201c an Sonne der Grund f\u00fcr die Symptome. \u201eVielmehr haben die Betroffenen eine Veranlagung f\u00fcr erh\u00f6hte Lichtempfindlichkeit insbesondere im UVA-Bereich \u2013 das langwellige UV-Licht-Spektrum, das meist keinen Sonnenbrand verursacht\u201c, erkl\u00e4rt Reuter. Er erg\u00e4nzt: \u201eOder das UV-Licht wandelt eine an sich harmlose Substanz in eine toxische oder allergisch sensibilisierende Substanz um.\u201c Abh\u00e4ngig vom Ausl\u00f6semechanismus k\u00f6nnen die Symptome ganz unterschiedlich sein.<\/p>\n<p>H\u00e4ufigste Form der Sonnenallergie: polymorphe Lichtdermatose<\/p>\n<p>Am h\u00e4ufigsten kommt die sogenannte polymorphe Lichtdermatose (PLD) vor. Sie trifft vor allem Menschen mit empfindlicher Haut. Ausl\u00f6ser sind hier allein UV-Strahlen. Sie k\u00f6nnen zu Quaddeln, Bl\u00e4schen oder juckenden roten Flecken f\u00fchren. \u201eBetroffen sind meist Stellen, die den Gro\u00dfteil des Jahres von Kleidung bedeckt und daher nicht an die Sonne gew\u00f6hnt sind. Dazu z\u00e4hlen beispielsweise Oberarme, Dekollet\u00e9, Schulterg\u00fcrtel oder Bauch\u201c, wei\u00df der DKV Experte. Eine Sonderform der PLD ist die Mallorca-Akne, an der meist Menschen mit fettiger Haut leiden. Treffen UV-Strahlen auf fetthaltige Sonnenschutz- oder andere K\u00f6rperpflegepr\u00e4parate, kommt es bei Betroffenen zu pickelartigen Kn\u00f6tchen. Darunter leiden fast ausschlie\u00dflich Urlauber in s\u00fcdlichen Feriengebieten.<\/p>\n<p>Phototoxische und photoallergische Reaktionen<\/p>\n<p>Wenig bekannt, aber nicht selten, sind phototoxische oder photoallergische Reaktionen. Sie treten auf, wenn sich bestimmte Inhaltsstoffe, beispielsweise von Medikamenten, Cremes oder Parf\u00fcms in der Haut ablagern und mit UV-Licht reagieren. M\u00f6glich ist auch eine Reaktion von Inhaltsstoffen aus Pflanzens\u00e4ften, zum Beispiel der Herkulesstaude. Typische Symptome sind dann ein Brennen oder Stechen, manchmal sogar eine Schwellung oder Blasenbildung der Haut sowie ein verst\u00e4rkter Sonnenbrand. Die Symptome treten nur an den Stellen der Haut auf, wo der Inhaltsstoff mit dem UV-Licht der Sonne reagieren und dadurch die sch\u00e4digende Substanz bilden konnte.<\/p>\n<p>Sonnenallergie vorbeugen<\/p>\n<p>Wer empfindlich auf Sonne reagiert, sollte seine Haut langsam an sie gew\u00f6hnen. PLD-Betroffene beispielsweise k\u00f6nnen ihre Symptome mit dem sogenannten \u201eHardening\u201c verbessern. Dabei setzen sie ihre Haut einer sich langsam steigernden UVA-Bestrahlung aus. Begleitend k\u00f6nnen sie B-Vitamine, Betakarotin und Kalzium einnehmen. Weiter gilt es, die intensive Mittagssonne sowie generell direkte Sonnenstrahlung zu meiden. Einen guten Schutz bieten leichte Kleidung und Kopfbedeckungen sowie Sonnenschutzpr\u00e4parate mit ausreichend hohem Lichtschutzfaktor \u2013 auch im Schatten. Wer an Mallorca-Akne leidet, sollte bereits kurz vor dem Urlaub seine Kosmetika auf fettfreie Produkte umstellen. Statt fettreicher Sonnencremes eignen sich beispielsweise spezielle Gele. Gut sind auch mineralische Filter wie Titandioxid und Zinkoxid. Sie wirken sofort nach dem Auftragen, bilden keine sch\u00e4dlichen Reaktionsprodukte und l\u00f6sen daher kaum allergische Reaktionen aus. \u201eWer w\u00e4hrend seines Urlaubs auf Medikamente angewiesen ist, sollte vorab mit seinem Arzt kl\u00e4ren, ob es m\u00f6glicherweise zu einer Wechselwirkung aufgrund der UV-Strahlen kommen kann. Ist das der Fall, kann er eventuell eine Alternative empfehlen\u201c, r\u00e4t der DKV Experte. Zudem ist es allgemein sinnvoll, vor und w\u00e4hrend des Sonnenbadens auf Parf\u00fcm, Seifen und Rasierwasser zu verzichten. Gartenliebhaber sollten sich \u00fcber Pflanzen informieren, die phototoxische Reaktionen ausl\u00f6sen k\u00f6nnen. \u201eKommt es trotz aller Vorsichtsma\u00dfnahmen zu Reaktionen der Haut, k\u00f6nnen k\u00fchlende Umschl\u00e4ge oder rezeptfreie Antihistaminika beziehungsweise Kortison-Gele aus der Apotheke Linderung verschaffen\u201c, wei\u00df Dr. Reuter.<\/p>\n<p>Unterschied zum Sonnenbrand<\/p>\n<p>F\u00fcr Sonnenbrand und Sonnenallergie sind zwar in beiden F\u00e4llen UV-Strahlen verantwortlich, es gibt aber einige Unterschiede: Bei einem Sonnenbrand ist die Haut oft gro\u00dffl\u00e4chig ger\u00f6tet, sie brennt, spannt und juckt. Erste Anzeichen zeigen sich etwa drei bis f\u00fcnf Stunden nach dem Sonnenbad. Die Beschwerden klingen in der Regel innerhalb von drei Tagen ab, nach etwa einer Woche sch\u00e4lt sich die Haut. \u201eBei starken Verbrennungen, die mit Schwindel und \u00dcbelkeit einhergehen, sollten Betroffene unbedingt einen Arzt aufsuchen\u201c, so Reuter. Bei einer Sonnenallergie dagegen kommen je nach Art R\u00f6tungen, Bl\u00e4schen, Quaddeln oder Kn\u00f6tchen vor. Die jeweilige Fl\u00e4chenverteilung und der Schweregrad der Hautver\u00e4nderungen helfen bei der Diagnose. Der Juckreiz ist meist st\u00e4rker als bei einem Sonnenbrand. Bis sich die ersten Beschwerden zeigen, k\u00f6nnen mitunter einige Stunden bis sogar Tage vergehen. Au\u00dferdem dauert es zumeist mehrere Tage, bis die Beschwerden abklingen. Wer zum ersten Mal Anzeichen einer Sonnenallergie bemerkt, sollte ebenfalls einen Arzt aufsuchen. Dieser kann dann feststellen, um welche Art der Sonnenallergie es sich handelt und dem Patienten eine geeignete Therapie empfehlen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Herzogtum Lauenburg (pm). So sch\u00f6n es ist, in der Sonne zu liegen \u2013 manchmal endet ein ausgiebiges Sonnenbad mit R\u00f6tungen, juckenden Hautstellen oder Pusteln. Solche Symptome k\u00f6nnen auf eine Sonnenallergie hinweisen. Was das ist, wie Betroffene vorbeugen k\u00f6nnen und was der Unterschied ist zu einem Sonnenbrand, wei\u00df Dr. Wolfgang Reuter, Gesundheitsexperte der DKV. Was ist [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24408,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[75],"tags":[1245],"class_list":["post-24407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesundheit","tag-sonnenallergie"],"_links":{"self":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/24407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/comments?post=24407"}],"version-history":[{"count":1,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/24407\/revisions"}],"predecessor-version":[{"id":24409,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/24407\/revisions\/24409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media\/24408"}],"wp:attachment":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media?parent=24407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/categories?post=24407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/tags?post=24407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}