{"id":18804,"date":"2019-11-09T10:59:49","date_gmt":"2019-11-09T08:59:49","guid":{"rendered":"https:\/\/herzogtum-direkt.de\/?p=18804"},"modified":"2019-11-09T10:59:49","modified_gmt":"2019-11-09T08:59:49","slug":"schraege-voegel-gefiederte-nachbarn-in-krummesse","status":"publish","type":"post","link":"https:\/\/herzogtum-direkt.de\/index.php\/2019\/11\/09\/schraege-voegel-gefiederte-nachbarn-in-krummesse\/","title":{"rendered":"&#8218;Schr\u00e4ge V\u00f6gel &#8211; gefiederte Nachbarn&#8216; in Krummesse"},"content":{"rendered":"<figure id=\"attachment_18805\" aria-describedby=\"caption-attachment-18805\" style=\"width: 241px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/2021.herzogtum-direkt.de\/wp-content\/uploads\/2019\/11\/Dr.Uwe-Westphal.jpg\"><img decoding=\"async\" class=\" wp-image-18805\" src=\"https:\/\/2021.herzogtum-direkt.de\/wp-content\/uploads\/2019\/11\/Dr.Uwe-Westphal-201x300.jpg\" alt=\"\" width=\"241\" height=\"360\" srcset=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2019\/11\/Dr.Uwe-Westphal-201x300.jpg 201w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2019\/11\/Dr.Uwe-Westphal-281x420.jpg 281w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2019\/11\/Dr.Uwe-Westphal.jpg 500w\" sizes=\"(max-width: 241px) 100vw, 241px\" \/><\/a><figcaption id=\"caption-attachment-18805\" class=\"wp-caption-text\">Biologe und<br \/>Vogelstimmenimitator Dr. Uwe Westphal. Foto: hfr<\/figcaption><\/figure>\n<p><strong>Krummesse (pm).<\/strong> Um &#8222;Schr\u00e4ge V\u00f6gel &#8211; gefiederte Nachbarn&#8220; geht es am Freitag, 22. November, um 19 Uhr im D\u00f6rpshuus Krummesse. Diese Lesung der besonderen Art ist von und mit dem Biologen und Vogelstimmenimitator Dr. Uwe Westphal.<\/p>\n<p>Kennen Sie die Rohrdommel, den Ziegenmelker oder den Wendehals? G\u00e4ste des Vortrags erfahren mehr \u00fcber das geheimnisvolle Leben dieser und anderer seltener, heimischer Vogelarten. Dr. Uwe Westphal wird kuriose Details und Erlebnisse sowie unterhaltsame<br \/>\nAnekdoten erz\u00e4hlen. Wussten Sie dass der Zaunk\u00f6nig stets mehrere Nester baut und sich M\u00e4tressen leistet? Oder dass der Raubw\u00fcrger kein Schwerverbrecher, sondern ein Singvogel ist, der Kleinv\u00f6gel und M\u00e4use jagt und auf Dornen spie\u00dft? Deutschlands bekanntester Vogelkundler und Tierstimmenimitatorwird die vorgestellten V\u00f6gel mit seiner Stimme lebendig werden lassen.<\/p>\n<p>Seit 50 Jahren \u00fcbt Westphal schon und beherrscht rund 130 Vogelstimmen. Dies und noch viel mehr vermittelt der Referent auf unnachahmliche Art locker und trotzdem kompetent, humorvoll und aus reichem Erfahrungsschatz sch\u00f6pfend.<\/p>\n<p>Karten gibt es an der Abendkasse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Krummesse (pm). Um &#8222;Schr\u00e4ge V\u00f6gel &#8211; gefiederte Nachbarn&#8220; geht es am Freitag, 22. November, um 19 Uhr im D\u00f6rpshuus Krummesse. Diese Lesung der besonderen Art ist von und mit dem Biologen und Vogelstimmenimitator Dr. Uwe Westphal. Kennen Sie die Rohrdommel, den Ziegenmelker oder den Wendehals? G\u00e4ste des Vortrags erfahren mehr \u00fcber das geheimnisvolle Leben dieser [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18805,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[65],"tags":[177],"class_list":["post-18804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amt-berkenthin","tag-krummesse"],"_links":{"self":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/18804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/comments?post=18804"}],"version-history":[{"count":1,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/18804\/revisions"}],"predecessor-version":[{"id":18806,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/18804\/revisions\/18806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media\/18805"}],"wp:attachment":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media?parent=18804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/categories?post=18804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/tags?post=18804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}