{"id":15315,"date":"2019-06-27T10:19:17","date_gmt":"2019-06-27T08:19:17","guid":{"rendered":"https:\/\/herzogtum-direkt.de\/?p=15315"},"modified":"2019-06-27T10:19:17","modified_gmt":"2019-06-27T08:19:17","slug":"neuer-turmwaechter-in-aumuehle","status":"publish","type":"post","link":"https:\/\/herzogtum-direkt.de\/index.php\/2019\/06\/27\/neuer-turmwaechter-in-aumuehle\/","title":{"rendered":"Neuer &#8218;Turmw\u00e4chter&#8216; in Aum\u00fchle"},"content":{"rendered":"<figure id=\"attachment_15316\" aria-describedby=\"caption-attachment-15316\" style=\"width: 225px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/2021.herzogtum-direkt.de\/wp-content\/uploads\/2019\/06\/Erhard-Bartels-Aum\u00fchle-e1561623501297.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-15316\" src=\"https:\/\/2021.herzogtum-direkt.de\/wp-content\/uploads\/2019\/06\/Erhard-Bartels-Aum\u00fchle-e1561623501297-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2019\/06\/Erhard-Bartels-Aum\u00fchle-e1561623501297-225x300.jpg 225w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2019\/06\/Erhard-Bartels-Aum\u00fchle-e1561623501297-768x1024.jpg 768w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2019\/06\/Erhard-Bartels-Aum\u00fchle-e1561623501297-696x928.jpg 696w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2019\/06\/Erhard-Bartels-Aum\u00fchle-e1561623501297-1068x1424.jpg 1068w, https:\/\/herzogtum-direkt.de\/wp-content\/uploads\/2019\/06\/Erhard-Bartels-Aum\u00fchle-e1561623501297-315x420.jpg 315w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><figcaption id=\"caption-attachment-15316\" class=\"wp-caption-text\">Erhard Bartels aus Aum\u00fchle. Foto: hfr<\/figcaption><\/figure>\n<p><strong>Aum\u00fchle (pm).<\/strong> Seit diesem Monat hat Aum\u00fchle einen neuen Verantwortlichen f\u00fcr das Aum\u00fchler Wahrzeichen, den Bismarck-Turm: Erhard, genannt Ede, Bartels hat sich bereit erkl\u00e4rt, diese Aufgabe von Gerd M\u00f6ller zu \u00fcbernehmen. Damit ist auch ein nahtloser \u00dcbergang f\u00fcr die im Turm beheimatete B\u00fccherei gew\u00e4hrleistet.<\/p>\n<p>Zur Erinnerung: Auf Initiative von Emil Specht wurde 1898\/99 der Bismarck-Turm vom Architekten Hermann Schomburgk f\u00fcr 45Tsd Mark errichtet und am 12. Juli 1901 eingeweiht. Zun\u00e4chst als Wasser- und Aussichtsturm inklusive Bismarck-B\u00fccherei und Bismarck-Museum.<\/p>\n<p>Es folgten, nach \u00dcbernahme des Turms seitens der Gemeinde, Jahre der unterschiedlichsten Anforderungen \u2013 bis hin zur aktuellen Nutzung f\u00fcr Mobilfunkantennen seit 1998. Seit 1999 steht der Bismarckturm unter Denkmalschutz.<\/p>\n<p>&#8222;Wir bedanken uns bei Gerd M\u00f6ller f\u00fcr seinen liebevollen Einsatz und danken unserem CDU-Mitglied und ehemaligen Wehrf\u00fchrer unserer Freiwilligen Feuerwehr Erhard Bartels daf\u00fcr, dass er sich f\u00fcr diese Aufgabe bereit erkl\u00e4rt hat&#8220;, hei\u00dft es aus den Reihen der CDU Aum\u00fchle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aum\u00fchle (pm). Seit diesem Monat hat Aum\u00fchle einen neuen Verantwortlichen f\u00fcr das Aum\u00fchler Wahrzeichen, den Bismarck-Turm: Erhard, genannt Ede, Bartels hat sich bereit erkl\u00e4rt, diese Aufgabe von Gerd M\u00f6ller zu \u00fcbernehmen. Damit ist auch ein nahtloser \u00dcbergang f\u00fcr die im Turm beheimatete B\u00fccherei gew\u00e4hrleistet. Zur Erinnerung: Auf Initiative von Emil Specht wurde 1898\/99 der Bismarck-Turm [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15316,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[63,73],"tags":[134,1955],"class_list":["post-15315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-herzogtum-lauenburg","category-landleute","tag-aumuehle","tag-cdu-aumuehle"],"_links":{"self":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/15315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/comments?post=15315"}],"version-history":[{"count":1,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/15315\/revisions"}],"predecessor-version":[{"id":15317,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/15315\/revisions\/15317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media\/15316"}],"wp:attachment":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media?parent=15315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/categories?post=15315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/tags?post=15315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}