{"id":1353,"date":"2018-03-10T06:52:31","date_gmt":"2018-03-10T06:52:31","guid":{"rendered":"http:\/\/hd.eu-mart.de\/?p=1353"},"modified":"2018-03-09T21:00:23","modified_gmt":"2018-03-09T21:00:23","slug":"alle-jahre-wieder-wertholzversteigerung-aus-lauenburgischen-waeldern-in-lanken","status":"publish","type":"post","link":"https:\/\/herzogtum-direkt.de\/index.php\/2018\/03\/10\/alle-jahre-wieder-wertholzversteigerung-aus-lauenburgischen-waeldern-in-lanken\/","title":{"rendered":"Alle Jahre wieder \u2013 Wertholzversteigerung aus lauenburgischen W\u00e4ldern in Lanken"},"content":{"rendered":"<p>Lanken (pm). Die wertvollsten H\u00f6lzer des winterlichen Holzeinschlags wurden auch in diesem Jahr in bew\u00e4hrter Tradition einem \u00fcberregionalen Bieterkreis auf dem Lagerplatz in Lanken angeboten und nach H\u00f6chstgebot ver\u00e4u\u00dfert. Insgesamt standen 460 St\u00e4mme, gr\u00f6\u00dftenteils von Laubb\u00e4umen, zum Verkauf.<\/p>\n<p>Den gr\u00f6\u00dften Anteil des Wertholzes macht dabei mit mehr als 80% das Eichenholz aus. Au\u00dferdem kamen noch Esche, Ahorn, Kirsche und einige Nadelh\u00f6lzer zum Verkauf. Der Gesamterl\u00f6s belief sich in diesem Jahr f\u00fcr die teilnehmenden Waldbesitzer auf \u00fcber 500.000 Euro. Die Einnahmen werden im laufenden Jahr etwa in die Unterhaltung der Waldwege gesteckt um Waldbesuchern einen besseren Zugang zum Wald zu erm\u00f6glichen. Aber nicht nur die Wege stehen im Fokus des Eigenbetriebes Kreisforsten. Es sollen au\u00dferdem B\u00e4nke bereitgestellt und die vorhandenen Waldsinnespfade unterhalten werden.<\/p>\n<p>Nahezu 90% der angebotenen H\u00f6lzer stammten aus kreiseigenen W\u00e4ldern. Diese B\u00e4ume wurden nach einer eingehenden Beurteilung ihres Wertes, Alters und Gesundheitszustandes einzeln den Best\u00e4nden entnommen. Grundlage hierf\u00fcr bildet eine Kartierung aller wertvollen Eichen im Kreiswald. Dadurch wird eine nachhaltige Ernte besonders starker B\u00e4ume \u00fcber Jahrzehnte sichergestellt. Etwa 15% dieser B\u00e4ume wurden bei der Kartierung hingegen als sogenannte Habitatb\u00e4ume ausgewiesen. Diese verbleiben dauerhaft in ihrem \u00d6kosystem und stehen dann unter lebenslangem Schutz.<\/p>\n<p>\u201eEs ist schon eine Besonderheit und Ausdruck der vorbildlichen Bewirtschaftung durch viele Generationen lauenburgischer F\u00f6rster, dass ein so kleiner Betrieb j\u00e4hrlich eine solche Menge wertvoller, starker B\u00e4ume anbieten kann.\u201c sagt Jan St\u00e4cker, Kreisrevierf\u00f6rster in Niendorf. \u201eDies gelingt aber nur durch Einhaltung des Nachhaltigkeitsprinzips und den vorsichtigen Umgang mit unserem Starkholz. Danach handeln alle unsere Revierleiter\u201c, so St\u00e4cker weiter.<\/p>\n<p>Der wertvollste Stamm der Submission kam in diesem Jahr aus dem Wald der Stadt M\u00f6lln, er erzielte einen Erl\u00f6s von 1.589 Euro pro Kubikmeter. Dabei wurde dieser Baum nicht gezielt ausgew\u00e4hlt sondern war ein Opfer des Herbststurms \u201eXavier\u201c.<\/p>\n<p>Noch liegen die verkauften St\u00e4mme auf dem Lagerplatz in Lanken. Die K\u00e4ufer werden aber bald mit dem Abtransport ihrer H\u00f6lzer beginnen. Wer sich also noch ein Bild dieser \u201eAush\u00e4ngeschilder\u201c unserer heimischen W\u00e4lder machen m\u00f6chte, sollte sich mit einem Spaziergang \u00fcber den Lagerplatz beeilen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lanken (pm). Die wertvollsten H\u00f6lzer des winterlichen Holzeinschlags wurden auch in diesem Jahr in bew\u00e4hrter Tradition einem \u00fcberregionalen Bieterkreis auf dem Lagerplatz in Lanken angeboten und nach H\u00f6chstgebot ver\u00e4u\u00dfert. Insgesamt standen 460 St\u00e4mme, gr\u00f6\u00dftenteils von Laubb\u00e4umen, zum Verkauf. Den gr\u00f6\u00dften Anteil des Wertholzes macht dabei mit mehr als 80% das Eichenholz aus. Au\u00dferdem kamen noch [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1354,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[67,63],"tags":[],"class_list":["post-1353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amt-sandesneben-nusse","category-herzogtum-lauenburg"],"_links":{"self":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/1353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/comments?post=1353"}],"version-history":[{"count":1,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/1353\/revisions"}],"predecessor-version":[{"id":1355,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/posts\/1353\/revisions\/1355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media\/1354"}],"wp:attachment":[{"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/media?parent=1353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/categories?post=1353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/herzogtum-direkt.de\/index.php\/wp-json\/wp\/v2\/tags?post=1353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}